{"id":14345,"date":"2018-11-22T11:02:30","date_gmt":"2018-11-22T10:02:30","guid":{"rendered":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero-3\/"},"modified":"2025-01-20T15:49:37","modified_gmt":"2025-01-20T14:49:37","slug":"clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero-3","status":"publish","type":"post","link":"https:\/\/www.aliberico.com\/fr\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero-3\/","title":{"rendered":"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-3014\" src=\"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg\" alt=\"\" width=\"770\" height=\"345\" \/><\/p>\n<h5>The award ceremony took place within the framework of the Night of the Economy, an event promoted by El Economista chaired by the Spanish Minister of Economy and Business, Nadia Calvi\u00f1o<\/h5>\n<p>Madrid, November 22nd.- Clemente Gonz\u00e1lez Soler, founder, owner and president of Alib\u00e9rico, the industrial and technological group specialized in the manufacture of semi-processed aluminium products, has been distinguished by the newspaper El Economista as the Most Relevant Economic and Financial Personality Award of the Year, for having converted his firm into the first Spanish private group and the first European family group within the aluminium sector.<\/p>\n<p>The award ceremony took place in the framework of the gala Night of the Economy, an event held at the headquarters of CaixaForum, in Madrid, which was chaired by the Spanish Minister of Economy and Business, Nadia Calvi\u00f1o. The call, which reaches its eighth edition this year and promoted by the EcoPrensa, presided by Alfonso de Salas, was attended by numerous personalities of political, economic and social life.<\/p>\n<p>Clemente Gonz\u00e1lez Soler founded Grupo Alib\u00e9rico in 1997, and since its inception it has been characterized by its great capacity for growth, innovation and internationalization, to become one of the world&rsquo;s leading references in the manufacture of semi-processed and technologically advanced aluminium products. The Group currently comprises 35 companies with 17 factories on four continents, 10 of them in Spain.<\/p>\n<p>The Industrial Group operates in the sectors of food packaging , building, surface treatment, transport, industry and renewable energy. It exports 70% of its turnover to more than 70 countries on 5 continents and directly employs more than 1,200 people.<\/p>\n<p>The jury of the award has also recognized Clemente Gonz\u00e1lez Soler as an exemple of entrepreneurship, supported by deeply held principles and values, and his role in the defense and promotion of a strong and independent civil society. This conviction has led him to exercise an active presence in various business associations. Currently, he is a Member of the Board of Directors of the Family Business Institute; and Member of the CEOE Executive Committee.<\/p>\n<p>In the same way, Clemente Gonz\u00e1lez Soler turns his experience and vision into different collective projects. For two years, he has been president of the Executive Committee of IFEMA and, as a professor at the EDEM business school and other academic institutions, he has a strong commitment to university education and senior management.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The award ceremony took place within the framework of the Night of the Economy, an event promoted by El Economista chaired by the Spanish Minister of Economy and Business, Nadia Calvi\u00f1o Madrid, November 22nd.- Clemente Gonz\u00e1lez Soler, founder, owner and president of Alib\u00e9rico, the industrial and technological group specialized in the manufacture of semi-processed aluminium [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14341,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-14345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero - Alib\u00e9rico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero - Alib\u00e9rico\" \/>\n<meta property=\"og:description\" content=\"The award ceremony took place within the framework of the Night of the Economy, an event promoted by El Economista chaired by the Spanish Minister of Economy and Business, Nadia Calvi\u00f1o Madrid, November 22nd.- Clemente Gonz\u00e1lez Soler, founder, owner and president of Alib\u00e9rico, the industrial and technological group specialized in the manufacture of semi-processed aluminium [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/\" \/>\n<meta property=\"og:site_name\" content=\"Alib\u00e9rico\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-22T10:02:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-20T14:49:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jcalero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"jcalero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/\"},\"author\":{\"name\":\"jcalero\",\"@id\":\"https:\/\/www.aliberico.com\/#\/schema\/person\/4cae64fe43e74920f00faee246999d7c\"},\"headline\":\"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero\",\"datePublished\":\"2018-11-22T10:02:30+00:00\",\"dateModified\":\"2025-01-20T14:49:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/\"},\"wordCount\":419,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.aliberico.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/\",\"url\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/\",\"name\":\"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero - Alib\u00e9rico\",\"isPartOf\":{\"@id\":\"https:\/\/www.aliberico.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg\",\"datePublished\":\"2018-11-22T10:02:30+00:00\",\"dateModified\":\"2025-01-20T14:49:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#primaryimage\",\"url\":\"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg\",\"contentUrl\":\"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg\",\"width\":770,\"height\":345},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.aliberico.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aliberico.com\/#website\",\"url\":\"https:\/\/www.aliberico.com\/\",\"name\":\"Alib\u00e9rico\",\"description\":\"L\u00edderes en Aluminio\",\"publisher\":{\"@id\":\"https:\/\/www.aliberico.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aliberico.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.aliberico.com\/#organization\",\"name\":\"Alib\u00e9rico\",\"url\":\"https:\/\/www.aliberico.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.aliberico.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.aliberico.com\/wp-content\/uploads\/2023\/11\/Logo-Aliberico.png\",\"contentUrl\":\"https:\/\/www.aliberico.com\/wp-content\/uploads\/2023\/11\/Logo-Aliberico.png\",\"width\":1726,\"height\":641,\"caption\":\"Alib\u00e9rico\"},\"image\":{\"@id\":\"https:\/\/www.aliberico.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.aliberico.com\/#\/schema\/person\/4cae64fe43e74920f00faee246999d7c\",\"name\":\"jcalero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.aliberico.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a651bcd7a6a0b28628a3885d1790b638ea432bfebcc2d618d9b74cf248463466?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a651bcd7a6a0b28628a3885d1790b638ea432bfebcc2d618d9b74cf248463466?s=96&d=mm&r=g\",\"caption\":\"jcalero\"},\"sameAs\":[\"https:\/\/www.aliberico.com\"],\"url\":\"https:\/\/www.aliberico.com\/fr\/author\/jcalero\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero - Alib\u00e9rico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/","og_locale":"fr_FR","og_type":"article","og_title":"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero - Alib\u00e9rico","og_description":"The award ceremony took place within the framework of the Night of the Economy, an event promoted by El Economista chaired by the Spanish Minister of Economy and Business, Nadia Calvi\u00f1o Madrid, November 22nd.- Clemente Gonz\u00e1lez Soler, founder, owner and president of Alib\u00e9rico, the industrial and technological group specialized in the manufacture of semi-processed aluminium [&hellip;]","og_url":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/","og_site_name":"Alib\u00e9rico","article_published_time":"2018-11-22T10:02:30+00:00","article_modified_time":"2025-01-20T14:49:37+00:00","og_image":[{"width":770,"height":345,"url":"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg","type":"image\/jpeg"}],"author":"jcalero","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"jcalero","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#article","isPartOf":{"@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/"},"author":{"name":"jcalero","@id":"https:\/\/www.aliberico.com\/#\/schema\/person\/4cae64fe43e74920f00faee246999d7c"},"headline":"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero","datePublished":"2018-11-22T10:02:30+00:00","dateModified":"2025-01-20T14:49:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/"},"wordCount":419,"commentCount":0,"publisher":{"@id":"https:\/\/www.aliberico.com\/#organization"},"image":{"@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/","url":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/","name":"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero - Alib\u00e9rico","isPartOf":{"@id":"https:\/\/www.aliberico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#primaryimage"},"image":{"@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg","datePublished":"2018-11-22T10:02:30+00:00","dateModified":"2025-01-20T14:49:37+00:00","breadcrumb":{"@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#primaryimage","url":"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg","contentUrl":"https:\/\/www.aliberico.com\/wp-content\/uploads\/2025\/01\/premio-eleconomista-Clemente-Gonzalez-Soler.jpg","width":770,"height":345},{"@type":"BreadcrumbList","@id":"https:\/\/www.aliberico.com\/clemente-gonzalez-soler-premio-personalidad-mas-relevante-del-ano-en-el-ambito-economico-y-financiero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aliberico.com\/fr\/"},{"@type":"ListItem","position":2,"name":"CLEMENTE GONZ\u00c1LEZ SOLER, Presidente del Grupo Alib\u00e9rico, Premio a la Personalidad m\u00e1s Relevante del A\u00f1o en el \u00e1mbito Econ\u00f3mico y Financiero"}]},{"@type":"WebSite","@id":"https:\/\/www.aliberico.com\/#website","url":"https:\/\/www.aliberico.com\/","name":"Alib\u00e9rico","description":"L\u00edderes en Aluminio","publisher":{"@id":"https:\/\/www.aliberico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aliberico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.aliberico.com\/#organization","name":"Alib\u00e9rico","url":"https:\/\/www.aliberico.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.aliberico.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.aliberico.com\/wp-content\/uploads\/2023\/11\/Logo-Aliberico.png","contentUrl":"https:\/\/www.aliberico.com\/wp-content\/uploads\/2023\/11\/Logo-Aliberico.png","width":1726,"height":641,"caption":"Alib\u00e9rico"},"image":{"@id":"https:\/\/www.aliberico.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.aliberico.com\/#\/schema\/person\/4cae64fe43e74920f00faee246999d7c","name":"jcalero","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.aliberico.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a651bcd7a6a0b28628a3885d1790b638ea432bfebcc2d618d9b74cf248463466?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a651bcd7a6a0b28628a3885d1790b638ea432bfebcc2d618d9b74cf248463466?s=96&d=mm&r=g","caption":"jcalero"},"sameAs":["https:\/\/www.aliberico.com"],"url":"https:\/\/www.aliberico.com\/fr\/author\/jcalero\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/posts\/14345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/comments?post=14345"}],"version-history":[{"count":0,"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/posts\/14345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/media\/14341"}],"wp:attachment":[{"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/media?parent=14345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/categories?post=14345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aliberico.com\/fr\/wp-json\/wp\/v2\/tags?post=14345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}